{"id":27,"count":2,"description":"","link":"https:\/\/www.lovesail.com\/ls-news\/tag\/volvo-ocean-race\/","name":"Volvo Ocean Race","slug":"volvo-ocean-race","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.9 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Volvo Ocean Race Archives - news<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Volvo Ocean Race Archives\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.lovesail.com\/ls-news\/tag\/volvo-ocean-race\/\" \/>\n<meta property=\"og:site_name\" content=\"news\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www.lovesail.com\\\/ls-news\\\/tag\\\/volvo-ocean-race\\\/\",\"url\":\"https:\\\/\\\/www.lovesail.com\\\/ls-news\\\/tag\\\/volvo-ocean-race\\\/\",\"name\":\"Volvo Ocean Race Archives - news\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.lovesail.com\\\/ls-news\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.lovesail.com\\\/ls-news\\\/tag\\\/volvo-ocean-race\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.lovesail.com\\\/ls-news\\\/tag\\\/volvo-ocean-race\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.lovesail.com\\\/ls-news\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Volvo Ocean Race\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.lovesail.com\\\/ls-news\\\/#website\",\"url\":\"https:\\\/\\\/www.lovesail.com\\\/ls-news\\\/\",\"name\":\"Lovesail.com\",\"description\":\"News, stories and articles from Lovesail.com \u2014 the dating and social networking site for sailing enthusiasts.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.lovesail.com\\\/ls-news\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.lovesail.com\\\/ls-news\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.lovesail.com\\\/ls-news\\\/#organization\",\"name\":\"lovesail\",\"url\":\"https:\\\/\\\/www.lovesail.com\\\/ls-news\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/www.lovesail.com\\\/ls-news\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/www.lovesail.com\\\/ls-news\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/new-logo-2025-Main.jpg?fit=300%2C70&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/www.lovesail.com\\\/ls-news\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/new-logo-2025-Main.jpg?fit=300%2C70&ssl=1\",\"width\":300,\"height\":70,\"caption\":\"lovesail\"},\"image\":{\"@id\":\"https:\\\/\\\/www.lovesail.com\\\/ls-news\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/LoveSail\",\"https:\\\/\\\/x.com\\\/lovesail\",\"https:\\\/\\\/www.instagram.com\\\/_lovesail\",\"https:\\\/\\\/www.pinterest.co.uk\\\/Lovesail\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCIbs7Pt9pogR-cIkwiIekMQ\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Volvo Ocean Race Archives - news","robots":{"index":"noindex","follow":"follow"},"og_locale":"en_GB","og_type":"article","og_title":"Volvo Ocean Race Archives","og_url":"https:\/\/www.lovesail.com\/ls-news\/tag\/volvo-ocean-race\/","og_site_name":"news","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.lovesail.com\/ls-news\/tag\/volvo-ocean-race\/","url":"https:\/\/www.lovesail.com\/ls-news\/tag\/volvo-ocean-race\/","name":"Volvo Ocean Race Archives - news","isPartOf":{"@id":"https:\/\/www.lovesail.com\/ls-news\/#website"},"breadcrumb":{"@id":"https:\/\/www.lovesail.com\/ls-news\/tag\/volvo-ocean-race\/#breadcrumb"},"inLanguage":"en-GB"},{"@type":"BreadcrumbList","@id":"https:\/\/www.lovesail.com\/ls-news\/tag\/volvo-ocean-race\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.lovesail.com\/ls-news\/"},{"@type":"ListItem","position":2,"name":"Volvo Ocean Race"}]},{"@type":"WebSite","@id":"https:\/\/www.lovesail.com\/ls-news\/#website","url":"https:\/\/www.lovesail.com\/ls-news\/","name":"Lovesail.com","description":"News, stories and articles from Lovesail.com \u2014 the dating and social networking site for sailing enthusiasts.","publisher":{"@id":"https:\/\/www.lovesail.com\/ls-news\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.lovesail.com\/ls-news\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/www.lovesail.com\/ls-news\/#organization","name":"lovesail","url":"https:\/\/www.lovesail.com\/ls-news\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/www.lovesail.com\/ls-news\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/www.lovesail.com\/ls-news\/wp-content\/uploads\/2025\/05\/new-logo-2025-Main.jpg?fit=300%2C70&ssl=1","contentUrl":"https:\/\/i0.wp.com\/www.lovesail.com\/ls-news\/wp-content\/uploads\/2025\/05\/new-logo-2025-Main.jpg?fit=300%2C70&ssl=1","width":300,"height":70,"caption":"lovesail"},"image":{"@id":"https:\/\/www.lovesail.com\/ls-news\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/LoveSail","https:\/\/x.com\/lovesail","https:\/\/www.instagram.com\/_lovesail","https:\/\/www.pinterest.co.uk\/Lovesail\/","https:\/\/www.youtube.com\/channel\/UCIbs7Pt9pogR-cIkwiIekMQ"]}]}},"_links":{"self":[{"href":"https:\/\/www.lovesail.com\/ls-news\/wp-json\/wp\/v2\/tags\/27","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lovesail.com\/ls-news\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.lovesail.com\/ls-news\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.lovesail.com\/ls-news\/wp-json\/wp\/v2\/posts?tags=27"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}